{"id":3970,"date":"2025-02-07T15:28:37","date_gmt":"2025-02-07T15:28:37","guid":{"rendered":"https:\/\/www.borderforensics.org\/news\/state-trafficking-expulsion-and-sale-of-migrants-from-tunisia-to-libya\/"},"modified":"2025-02-11T17:12:32","modified_gmt":"2025-02-11T17:12:32","slug":"statetrafficingreport","status":"publish","type":"update","link":"https:\/\/www.borderforensics.org\/fr\/actualites\/statetrafficingreport\/","title":{"rendered":"State Trafficking \u2013 Expulsion et vente de migrants de la Tunisie vers la Libye"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"576\" src=\"https:\/\/www.borderforensics.org\/app\/uploads\/2025\/02\/SchermataBase_video-1024x576.jpg\" alt=\"\" class=\"wp-image-3960\" srcset=\"https:\/\/www.borderforensics.org\/app\/uploads\/2025\/02\/SchermataBase_video-1024x576.jpg 1024w, https:\/\/www.borderforensics.org\/app\/uploads\/2025\/02\/SchermataBase_video-300x169.jpg 300w, https:\/\/www.borderforensics.org\/app\/uploads\/2025\/02\/SchermataBase_video-768x432.jpg 768w, https:\/\/www.borderforensics.org\/app\/uploads\/2025\/02\/SchermataBase_video-1536x864.jpg 1536w, https:\/\/www.borderforensics.org\/app\/uploads\/2025\/02\/SchermataBase_video.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Le rapport comprend 30 t\u00e9moignages de migrants qui ont \u00e9t\u00e9 expuls\u00e9s de Tunisie vers la Libye entre juin 2023 et novembre 2024, mettant en \u00e9vidence un trait saillant qui appara\u00eet dans leurs r\u00e9cits : la vente d&#8217;\u00eatres humains \u00e0 la fronti\u00e8re par les appareils policiers et militaires tunisiens ainsi que l&#8217;interconnexion entre l&#8217;infrastructure derri\u00e8re les expulsions et l&#8217;industrie de l&#8217;enl\u00e8vement dans les prisons libyennes. En ce sens, le rapport documente des \u00e9v\u00e9nements et des situations que les sciences sociales et le droit international qualifient de &#8220;crimes d&#8217;\u00c9tat&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-embed-handler wp-block-embed-embed-handler\"><div class=\"wp-block-embed__wrapper\">\n<div style=\"width: 640px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-3970-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/statetrafficking.net\/State-trafficking_01.mp4?_=1\" \/><a href=\"https:\/\/statetrafficking.net\/State-trafficking_01.mp4\">https:\/\/statetrafficking.net\/State-trafficking_01.mp4<\/a><\/video><\/div>\n<\/div><figcaption>T\u00e9moignage vid\u00e9o 1<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-embed-handler wp-block-embed-embed-handler\"><div class=\"wp-block-embed__wrapper\">\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-3970-2\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/statetrafficking.net\/State-trafficking_02.mp4?_=2\" \/><a href=\"https:\/\/statetrafficking.net\/State-trafficking_02.mp4\">https:\/\/statetrafficking.net\/State-trafficking_02.mp4<\/a><\/video><\/div>\n<\/div><figcaption>T\u00e9moignage vid\u00e9o 2<\/figcaption><\/figure>\n\n\n        <div class=\"bf-pullquote block w-screen py-20 md:py-40 px-3 md:px-[25vw] \n      diacritics-left pq-light      bg-blueGrey\" style=\"margin-block-start: 0;\">\n      <div class=\"block__paragraph\">\n        <p class=\"medium text-midnightBlue\">\n                    Nous nous sommes confi\u00e9s \u00e0 eux, car ce sont des autorit\u00e9s comp\u00e9tentes.  Ils ont mis tous les t\u00e9l\u00e9phones dans une bo\u00eete et ont pris l&#039;argent que nous avions. Il \u00e9tait environ 21 heures. Ils ont fini de nous fouiller, ont pris nos passeports et nous ont fait monter dans les bus. Si nous avions su, nous aurions pu r\u00e9sister.\u201d                  <\/p>\n      <\/div><!-- \/.block__paragraph -->\n    <\/div><!-- \/.block -->\n\n\n\n\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/www.borderforensics.org\/app\/uploads\/2025\/02\/StateTrafficking_FR_21012025_light-2.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of StateTrafficking report | fran\u00e7ais.\"><\/object><a id=\"wp-block-file--media-2d2d38e8-ba73-47ea-96fd-ebfc414c01c1\" href=\"https:\/\/www.borderforensics.org\/app\/uploads\/2025\/02\/StateTrafficking_FR_21012025_light-2.pdf\">StateTrafficking report | fran\u00e7ais<\/a><\/div>\n\n\n\n<p><strong>Site web du rapport :<\/strong><br><a href=\"https:\/\/statetrafficking.net\/\">https:\/\/statetrafficking.net<\/a><\/p>\n\n\n\n<p><strong>Contact :<\/strong><br>Press Office: <a href=\"mailto:info@asgi.it\">info@asgi.it<\/a><br>Contents Info: <a href=\"mailto:statetrafficking@onenetbeyond.org\">statetrafficking@onenetbeyond.org<\/a><\/p>\n","protected":false},"featured_media":0,"template":"","categories":[],"tags":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Jelka Kretzschmar","author_link":"https:\/\/www.borderforensics.org\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Le rapport comprend 30 t\u00e9moignages de migrants qui ont \u00e9t\u00e9 expuls\u00e9s de Tunisie vers la Libye entre juin 2023 et novembre 2024, mettant en \u00e9vidence un trait saillant qui appara\u00eet dans leurs r\u00e9cits : la vente d&#8217;\u00eatres humains \u00e0 la fronti\u00e8re par les appareils policiers et militaires tunisiens ainsi que l&#8217;interconnexion entre l&#8217;infrastructure derri\u00e8re les&hellip;","_links":{"self":[{"href":"https:\/\/www.borderforensics.org\/fr\/wp-json\/wp\/v2\/update\/3970"}],"collection":[{"href":"https:\/\/www.borderforensics.org\/fr\/wp-json\/wp\/v2\/update"}],"about":[{"href":"https:\/\/www.borderforensics.org\/fr\/wp-json\/wp\/v2\/types\/update"}],"version-history":[{"count":8,"href":"https:\/\/www.borderforensics.org\/fr\/wp-json\/wp\/v2\/update\/3970\/revisions"}],"predecessor-version":[{"id":4031,"href":"https:\/\/www.borderforensics.org\/fr\/wp-json\/wp\/v2\/update\/3970\/revisions\/4031"}],"wp:attachment":[{"href":"https:\/\/www.borderforensics.org\/fr\/wp-json\/wp\/v2\/media?parent=3970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.borderforensics.org\/fr\/wp-json\/wp\/v2\/categories?post=3970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.borderforensics.org\/fr\/wp-json\/wp\/v2\/tags?post=3970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}